{"id":1481,"date":"2025-09-12T10:21:37","date_gmt":"2025-09-12T09:21:37","guid":{"rendered":"https:\/\/www.livspain.com\/development\/zinnia\/"},"modified":"2025-11-18T13:07:11","modified_gmt":"2025-11-18T12:07:11","slug":"zinnia","status":"publish","type":"development","link":"https:\/\/www.livspain.com\/en\/development\/zinnia\/","title":{"rendered":"Zinnia"},"content":{"rendered":"\n<div class=\"wp-block-group ic-wrapper-title\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"233\" height=\"219\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/10\/mask.svg\" alt=\"\" class=\"wp-image-880\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<div class=\"wp-block-group container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading text-center\">Zinnia<\/h1>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Marbella<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-video\">\n  <video id=\"zinniaVideo\" autoplay muted preload=\"auto\" playsinline>\n    <source src=\"\/wp-content\/themes\/livspain\/videos\/zinnia-video.mp4\" type=\"video\/mp4\">\n    Tu navegador no soporta video HTML5.\n  <\/video>\n<\/figure>\n\n\n\n<figure class=\"wp-block-video d-none\"><video autoplay loop muted src=\"\/wp-content\/themes\/livspain\/videos\/zinnia-video.mp4\" playsinline><\/video><\/figure>\n\n\n\n<div class=\"wp-block-cover is-light d-none\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" class=\"wp-block-cover__image-background wp-image-1252 size-full\" alt=\"\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/zinnia.webp\" data-object-fit=\"cover\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/zinnia.webp 1080w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/zinnia-600x600.webp 600w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/zinnia-768x768.webp 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#9199a5\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group container caracteristicas\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">M\u00e1laga \u00b7 <strong>Marbella<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">New development in Marbella with Mediterranean essence<\/h2>\n\n\n\n<p class=\"single-price wp-block-paragraph\">FROM \u20ac 330,000 + VAT<\/p>\n\n\n\n<ul class=\"wp-block-list single-feat\">\n<li>In Marketing<\/li>\n\n\n\n<li>19 homes<\/li>\n\n\n\n<li>1-3 bedrooms<\/li>\n\n\n\n<li>from 79 m<sup>2<\/sup> surface<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zinnia<\/strong> is located in the heart of San Pedro Alc\u00e1ntara, just steps from the beach and offering spectacular <strong>views of the sea and Marbella\u2019s iconic La Concha mountain<\/strong>. With only 19 residences of 1, 2, and 3 bedrooms, this exclusive development delivers a vibrant, well-connected lifestyle just minutes from Puerto Ban\u00fas and everything that makes Marbella a unique destination on the Costa del Sol. Its premium communal areas transform everyday living into an experience of wellbeing and comfort.<\/p>\n\n\n\n<p class=\"ic-entrega wp-block-paragraph\"><strong>2027 completion<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:8%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top ic-contact-promo is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<h2 class=\"wp-block-heading\">Contact<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:zinnia@livspain.com\">zinnia@livspain.com<\/a><\/p>\n\n\n\n<p class=\"ic-phone wp-block-paragraph\"><a href=\"tel:0034951559595\">+34 951 55 95 95<\/a><\/p>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1564-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1564\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/development\/1481#wpcf7-f1564-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1564\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1564-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAAB1RRp93sjUlut9E\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n\n<div class=\"form-fields\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name &amp; Surname *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone *\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-md-6\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"1\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-12\">\n\t\t\t<div>\n\t\t\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"legal\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"legal\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and accept the <a href=\"\/en\/privacy-policy\/\" title=\"privacy-policy\" target=\"_blank\">privacy-policy<\/a> and the <a href=\"\/en\/legal-advice\/\" title=\"legal-advice\" target=\"_blank\">legal-advice<\/a> of this site. *<\/span><\/label><\/span><\/span><\/span><\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div>\n\t\t\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"commercial\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"commercial\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I agree to receive commercial information about real estate promotions, products, activities and services from LIV REAL ESTATE.<\/span><\/label><\/span><\/span><\/span><\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\/en\/thank-you\/\" type=\"hidden\" name=\"redirect_to\" \/><br \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group ic-bgcolour-blue ic-gallery\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"carousel3slide\">\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1361\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1358\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1.webp\" alt=\"\" class=\"wp-image-1363\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1-1200x849.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1-768x543.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/02_Exterior-fachada-trasera_01_SD_HD-1-1920x1358-1-1536x1086.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1365\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/03_Exterior-zona-comun-piscina_02_SD_HD-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1367\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/04_Exterior-piscina-cubierta_02_SD_HD-1-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1369\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/05_Exterior-terraza-atico_SD3_HD-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1371\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/06_Interior-salon_02_SD_HD-1-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1358\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1.webp\" alt=\"\" class=\"wp-image-1373\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1-1200x849.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1-768x543.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/07_Interior-cocina_02_SD_HD-1920x1358-1-1536x1086.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1358\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1.webp\" alt=\"\" class=\"wp-image-1375\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1-1200x849.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1-768x543.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/08_Interior-dormitorio-principal_01_SD_HD-1-1920x1358-1-1536x1086.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1377\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/09_Interior-gimnasio_SD_HD-1-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2400\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ.webp\" alt=\"\" class=\"wp-image-1379\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ-960x1200.webp 960w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ-1536x1920.webp 1536w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ-768x960.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ-1229x1536.webp 1229w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/10_Interior-bano_08_SD_HQ-1638x2048.webp 1638w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1.webp\" alt=\"\" class=\"wp-image-1381\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1-1200x675.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1-768x432.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/11_Interior-terraza-vivienda_04_SD_HD-1920x1080-1-1536x864.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1.webp\" alt=\"\" class=\"wp-image-1383\" srcset=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1.webp 1920w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1-1200x800.webp 1200w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1-768x512.webp 768w, https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/12_Interior-dormitorio-secundario_01_SD_HD-1-1920x1280-1-1536x1024.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/figure>\n\n\n\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group ic-bgcolour-blue\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"slick-variablewidth container\">\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/piscina-rooftop-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1343\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Rooftop pool with solarium<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/gimnasio-sauna-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1346\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fully equipped gym with sauna<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/garaje-trastero-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1332\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Parking and storage room<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/climatizacion-zinnia--600x600.jpg\" alt=\"\" class=\"wp-image-1334\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Advanced climate control<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/recarga-vehiculo-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1337\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Charging points for electric vehicles*<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/domotica-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1339\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Smart home system*<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/entorno-zinnia-600x600.jpg\" alt=\"\" class=\"wp-image-1341\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vibrant surroundings, just steps away from the beach<\/p>\n<\/div><\/div>\n\n\n\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group ic-bgcolour-blue pt-4\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"container wp-block-paragraph\">*Optional features<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group ic-bgcolour-blue\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">An exclusive retreat<br>in San Pedro Alc\u00e1ntara<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zinnia<\/strong> is one of <strong>Marbella\u2019s new developments<\/strong> that best embodies the fusion of exclusivity, location, and quality of life. Its setting in San Pedro Alc\u00e1ntara offers a unique lifestyle: the Mediterranean Sea just a short walk away, the vibrant atmosphere of Puerto Ban\u00fas only minutes from your door, and all essential services &#8211; schools, shops, restaurants, and healthcare &#8211; right at street level.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">With only 19 carefully designed residences, <strong>Zinnia<\/strong> provides an intimate and welcoming atmosphere, ideal for those seeking a contemporary home in a well-connected environment. The communal areas include a <strong>gym with sauna, a rooftop pool with solarium and panoramic views of the sea and mountains<\/strong>, as well as features tailored to modern living such as <strong>smart home technology, advanced climate control, and charging points for electric vehicles.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Every detail of the project has been conceived to ensure <strong>functionality, design, and comfort,<\/strong> creating a space where each day is lived with the calm of the Mediterranean and the vibrant energy of Marbella. More than just a home, Zinnia is an exclusive retreat on the Costa del Sol &#8211; a place to enjoy sunlight, the sea, and an incomparable lifestyle.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:10%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:90px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe src=\"\/tour-virtual\/index.htm\" title=\"Zinnia virtual tour\" width=\"100%\" class=\"tour-virtual\"><\/iframe>\n\n\n\n<figure class=\"wp-block-image size-full ic-360 d-none\"><a href=\"#\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"373\" src=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/thegrove-360.jpg\" alt=\"\" class=\"wp-image-1263\"\/><\/a><\/figure>\n\n\n\n<ul class=\"wp-block-list ic-links\">\n<li><a href=\"\/wp-content\/themes\/livspain\/pdf\/zinnia-brochure-ENG.pdf\">Commercial brochure<\/a><\/li>\n\n\n\n<li><a href=\"\/wp-content\/uploads\/2025\/11\/GENERALES_ZINNIA.pdf\">General plans<\/a><\/li>\n\n\n\n<li><a href=\"\/wp-content\/uploads\/2025\/11\/memoria_de_calidades_zinnia.pdf\">Quality report<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons ic-web is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/praxfer.com\/en\/development\/zinnia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Visit Zinnia website<\/a><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>19<\/li>\n<li>1-3<\/li>\n<li>Desde 79 m\u00b2<\/li>\n<\/ul>\n<p class=\"ic-price\">From \u20ac330,000 + VAT<\/p>\n<p class=\"ic-date\">2027 completion<\/p>\n","protected":false},"featured_media":1362,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[],"tags":[33,34],"dev-category":[20,21],"class_list":["post-1481","development","type-development","status-publish","has-post-thumbnail","hentry","tag-in-marketing","tag-works-started","dev-category-malaga","dev-category-marbella"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zinnia: New-build Development in Marbella | LIV Real Estate<\/title>\n<meta name=\"description\" content=\"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livspain.com\/en\/development\/zinnia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zinnia: New-build Development in Marbella | LIV Real Estate\" \/>\n<meta property=\"og:description\" content=\"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livspain.com\/en\/development\/zinnia\/\" \/>\n<meta property=\"og:site_name\" content=\"LIV Real Estate\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T12:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/\",\"url\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/\",\"name\":\"Zinnia: New-build Development in Marbella | LIV Real Estate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livspain.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\",\"datePublished\":\"2025-09-12T09:21:37+00:00\",\"dateModified\":\"2025-11-18T12:07:11+00:00\",\"description\":\"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livspain.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.livspain.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/development\\\/zinnia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Developments\",\"item\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zinnia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/\",\"name\":\"LIV Real Estate\",\"description\":\"LIV Real Estate\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#organization\"},\"alternateName\":\"LIV Real Estate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#organization\",\"name\":\"LIV REAL ESTATE\",\"alternateName\":\"LIV REAL ESTATE\",\"url\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livspain.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/thegroove.webp\",\"contentUrl\":\"https:\\\/\\\/www.livspain.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/thegroove.webp\",\"width\":2000,\"height\":1344,\"caption\":\"LIV REAL ESTATE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livspain.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zinnia: New-build Development in Marbella | LIV Real Estate","description":"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livspain.com\/en\/development\/zinnia\/","og_locale":"en_US","og_type":"article","og_title":"Zinnia: New-build Development in Marbella | LIV Real Estate","og_description":"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.","og_url":"https:\/\/www.livspain.com\/en\/development\/zinnia\/","og_site_name":"LIV Real Estate","article_modified_time":"2025-11-18T12:07:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/","url":"https:\/\/www.livspain.com\/en\/development\/zinnia\/","name":"Zinnia: New-build Development in Marbella | LIV Real Estate","isPartOf":{"@id":"https:\/\/www.livspain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/#primaryimage"},"image":{"@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp","datePublished":"2025-09-12T09:21:37+00:00","dateModified":"2025-11-18T12:07:11+00:00","description":"Zinnia offers 19 homes with 1, 2 and 3 bedrooms in Marbella, just steps from the beach and boasting spectacular views of the sea and La Concha mountain.","breadcrumb":{"@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livspain.com\/en\/development\/zinnia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/#primaryimage","url":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp","contentUrl":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/01_Exterior-fachada_02_SD_HD-1920x1080-1.webp","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livspain.com\/en\/development\/zinnia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livspain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Developments","item":"https:\/\/www.livspain.com\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Zinnia"}]},{"@type":"WebSite","@id":"https:\/\/www.livspain.com\/en\/#website","url":"https:\/\/www.livspain.com\/en\/","name":"LIV Real Estate","description":"LIV Real Estate","publisher":{"@id":"https:\/\/www.livspain.com\/en\/#organization"},"alternateName":"LIV Real Estate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livspain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.livspain.com\/en\/#organization","name":"LIV REAL ESTATE","alternateName":"LIV REAL ESTATE","url":"https:\/\/www.livspain.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.livspain.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/thegroove.webp","contentUrl":"https:\/\/www.livspain.com\/wp-content\/uploads\/2025\/09\/thegroove.webp","width":2000,"height":1344,"caption":"LIV REAL ESTATE"},"image":{"@id":"https:\/\/www.livspain.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/development\/1481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/development"}],"about":[{"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/types\/development"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/media\/1362"}],"wp:attachment":[{"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/media?parent=1481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/categories?post=1481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/tags?post=1481"},{"taxonomy":"dev-category","embeddable":true,"href":"https:\/\/www.livspain.com\/en\/wp-json\/wp\/v2\/dev-category?post=1481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}